{"id":14,"date":"2017-06-30T12:34:17","date_gmt":"2017-06-30T10:34:17","guid":{"rendered":"https:\/\/niveb.com\/?page_id=14"},"modified":"2024-07-18T09:21:00","modified_gmt":"2024-07-18T07:21:00","slug":"medicura-academy-2","status":"publish","type":"page","link":"https:\/\/niveb.com\/de_de\/","title":{"rendered":"Home"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"14\" class=\"elementor elementor-14\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-675d600 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"675d600\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d399203\" data-id=\"d399203\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-30d0d5b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"30d0d5b\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-816da3b\" data-id=\"816da3b\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e3f796a nomargin-h2 elementor-widget elementor-widget-heading\" data-id=\"e3f796a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Innovationen im Gesundheitswesen<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9e2075f elementor-widget elementor-widget-text-editor\" data-id=\"9e2075f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Niveb bietet eine Vielzahl von Schulungen zum Thema Kin\u00e4sthetik an, einem revolution\u00e4ren Ansatz f\u00fcr die Verlagerung Ihrer Klienten im Gesundheits- und Sozialwesen.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5125cc5 elementor-widget__width-auto elementor-widget elementor-widget-button\" data-id=\"5125cc5\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/niveb.com\/de_de\/scholingen\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Unsere Schulungen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-edbc68b\" data-id=\"edbc68b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2772cc88 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2772cc88\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-48dfb854\" data-id=\"48dfb854\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4bb88c5 elementor-widget elementor-widget-heading\" data-id=\"4bb88c5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Der Mensch als Ausgangspunkt f\u00fcr gute Pflege, damit diese sowohl f\u00fcr den Arbeitnehmer als auch f\u00fcr den Pflegebed\u00fcrftigen ges\u00fcnder und menschlicher wird.<\/span>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-31eb592 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"31eb592\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d74b263\" data-id=\"d74b263\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d3f8846 elementor-widget elementor-widget-heading\" data-id=\"d3f8846\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Bewegen Sie Ihren Kunden mit Leichtigkeit!<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d0c16fa elementor-widget-divider--separator-type-pattern elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"d0c16fa\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\" style=\"--divider-pattern-url: url(&quot;data:image\/svg+xml,%3Csvg xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039; preserveAspectRatio=&#039;none&#039; overflow=&#039;visible&#039; height=&#039;100%&#039; viewBox=&#039;0 0 24 24&#039; fill=&#039;none&#039; stroke=&#039;black&#039; stroke-width=&#039;3&#039; stroke-linecap=&#039;square&#039; stroke-miterlimit=&#039;10&#039;%3E%3Cpath d=&#039;M0,6c6,0,6,13,12,13S18,6,24,6&#039;\/%3E%3C\/svg%3E&quot;);\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5b07dab elementor-widget elementor-widget-text-editor\" data-id=\"5b07dab\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Niveb sorgt f\u00fcr diese Ver\u00e4nderung im Gesundheitswesen. Wie? Indem wir Schulungen anbieten, bei denen der Mensch mit seinen typischen Eigenschaften im Mittelpunkt steht. Ein Mensch, der sich bewegt, denkt, sucht, findet und autonom ist. Ein Mensch als Teamplayer, ein soziales Wesen: Eigenschaften, die im Gesundheitswesen, aber auch dar\u00fcber hinaus so wichtig sind. Menschen als Menschen bewegen, denken und handeln lassen, um die Gesundheit der Mitarbeiter und Patienten positiv zu beeinflussen. So machen wir gemeinsam das Gesundheitswesen effizienter.<\/p><p>Niveb fordert Sie heraus, noch effizienter zu werden, indem der Mensch in den Mittelpunkt gestellt wird.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1b8248f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1b8248f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d38bf23\" data-id=\"d38bf23\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8079d63 elementor-widget elementor-widget-heading\" data-id=\"8079d63\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Lernen Sie mit Leichtigkeit, Ihren Klienten zu bewegen.<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8dbd201 elementor-widget-divider--separator-type-pattern elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"8dbd201\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\" style=\"--divider-pattern-url: url(&quot;data:image\/svg+xml,%3Csvg xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039; preserveAspectRatio=&#039;none&#039; overflow=&#039;visible&#039; height=&#039;100%&#039; viewBox=&#039;0 0 24 24&#039; fill=&#039;none&#039; stroke=&#039;black&#039; stroke-width=&#039;3&#039; stroke-linecap=&#039;square&#039; stroke-miterlimit=&#039;10&#039;%3E%3Cpath d=&#039;M0,6c6,0,6,13,12,13S18,6,24,6&#039;\/%3E%3C\/svg%3E&quot;);\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b803e16 elementor-widget elementor-widget-text-editor\" data-id=\"b803e16\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Niveb bietet eine Vielzahl von Schulungen zum Thema Niveb-Kinaesthetics an, einem revolution\u00e4ren Ansatz im Gesundheits- und Sozialwesen. Aber was genau ist Niveb-Kinaesthetics?\u00a0<\/p><p class=\" translation-block\">Niveb-Kinaesthetics ist die Kunst, das K\u00f6nnen und die Wissenschaft menschlicher Bewegung. Es konzentriert sich darauf, wie Menschen ihren K\u00f6rper bewegen und wie diese Bewegungen optimiert werden k\u00f6nnen, um Gesundheit und Wohlbefinden zu verbessern. Der Kern von Niveb-Kinaesthetics liegt darin, sich der eigenen Bewegungen bewusst zu werden und zu lernen, diese Bewegungen zu verbessern, um physische Beschwerden zu reduzieren und die allgemeine Mobilit\u00e4t zu f\u00f6rdern. Dies ist besonders n\u00fctzlich im Gesundheitswesen, wo Patienten oft Unterst\u00fctzung bei allt\u00e4glichen Bewegungen und der Mobilit\u00e4t ben\u00f6tigen.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-04a5dae elementor-widget elementor-widget-button\" data-id=\"04a5dae\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/niveb.com\/de_de\/scholingen\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Unsere Schulungen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3bdbc0d elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"3bdbc0d\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-624ef27 elementor-grid-5 elementor-grid-tablet-3 elementor-grid-mobile-2 elementor-products-grid elementor-wc-products elementor-widget elementor-widget-woocommerce-products\" data-id=\"624ef27\" data-element_type=\"widget\" data-widget_type=\"woocommerce-products.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"woocommerce columns-5\"><ul class=\"products elementor-grid columns-5\">\n<li class=\"product type-product post-1656 status-publish first instock product_cat-ergotherapie product_cat-fysiotherapie product_cat-patiententransfer product_cat-verpleegkundige has-post-thumbnail purchasable product-type-simple\">\n\t<a href=\"https:\/\/niveb.com\/de_de\/produkt\/niveb-kinaesthetics-vervolgcursus-2026-06-09-leverkusen\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img fetchpriority=\"high\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/niveb.com\/wp-content\/uploads\/2022\/04\/4013-2-400x400.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/niveb.com\/wp-content\/uploads\/2022\/04\/4013-2-400x400.jpg 400w, https:\/\/niveb.com\/wp-content\/uploads\/2022\/04\/4013-2-150x150.jpg 150w, https:\/\/niveb.com\/wp-content\/uploads\/2022\/04\/4013-2-100x100.jpg 100w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><h2 class=\"woocommerce-loop-product__title\">Niveb-Kinaesthetics Vervolgcursus 2026-06-09 Leverkusen<\/h2>\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>395.00<\/bdi><\/span><\/span>\n<\/a><a href=\"?add-to-cart=1656\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_1656\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"1656\" data-product_sku=\"\" aria-label=\"In den Warenkorb legen: \u201eNiveb-Kinaesthetics Vervolgcursus 2026-06-09 Leverkusen\u201c\" rel=\"nofollow\" data-no-translation=\"\" data-trp-gettext=\"\" data-no-translation-aria-label=\"\">In den Warenkorb<\/a><span id=\"woocommerce_loop_add_to_cart_link_describedby_1656\" class=\"screen-reader-text\">\n\t<\/span>\n<\/li>\n<li class=\"product type-product post-1653 status-publish instock product_cat-ergotherapie product_cat-fysiotherapie product_cat-patiententransfer product_cat-verpleegkundige has-post-thumbnail purchasable product-type-simple\">\n\t<a href=\"https:\/\/niveb.com\/de_de\/produkt\/niveb-kinaesthetics-vervolgcursus-2026-11-17\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img fetchpriority=\"high\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/niveb.com\/wp-content\/uploads\/2022\/04\/4013-2-400x400.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/niveb.com\/wp-content\/uploads\/2022\/04\/4013-2-400x400.jpg 400w, https:\/\/niveb.com\/wp-content\/uploads\/2022\/04\/4013-2-150x150.jpg 150w, https:\/\/niveb.com\/wp-content\/uploads\/2022\/04\/4013-2-100x100.jpg 100w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><h2 class=\"woocommerce-loop-product__title\">Niveb-Kinaesthetics Vervolgcursus 2026-11-17 Leverkusen<\/h2>\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>395.00<\/bdi><\/span><\/span>\n<\/a><a href=\"?add-to-cart=1653\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_1653\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"1653\" data-product_sku=\"\" aria-label=\"In den Warenkorb legen: \u201eNiveb-Kinaesthetics Vervolgcursus 2026-11-17 Leverkusen\u201c\" rel=\"nofollow\" data-no-translation=\"\" data-trp-gettext=\"\" data-no-translation-aria-label=\"\">In den Warenkorb<\/a><span id=\"woocommerce_loop_add_to_cart_link_describedby_1653\" class=\"screen-reader-text\">\n\t<\/span>\n<\/li>\n<li class=\"product type-product post-1647 status-publish instock product_cat-ergotherapie product_cat-fysiotherapie product_cat-patiententransfer product_cat-verpleegkundige has-post-thumbnail virtual purchasable product-type-simple\">\n\t<a href=\"https:\/\/niveb.com\/de_de\/produkt\/niveb-kinaesthetics-basiscursus-2026-09-15\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/niveb.com\/wp-content\/uploads\/2025\/06\/NIVEB_DRK-400x400.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/niveb.com\/wp-content\/uploads\/2025\/06\/NIVEB_DRK-400x400.jpg 400w, https:\/\/niveb.com\/wp-content\/uploads\/2025\/06\/NIVEB_DRK-150x150.jpg 150w, https:\/\/niveb.com\/wp-content\/uploads\/2025\/06\/NIVEB_DRK-100x100.jpg 100w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><h2 class=\"woocommerce-loop-product__title\">Niveb-Kinaesthetics Basiscursus 2026-09-15 M\u00f6nchengladbach<\/h2>\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>395.00<\/bdi><\/span><\/span>\n<\/a><a href=\"?add-to-cart=1647\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_1647\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"1647\" data-product_sku=\"\" aria-label=\"In den Warenkorb legen: \u201eNiveb-Kinaesthetics Basiscursus 2026-09-15 M\u00f6nchengladbach\u201c\" rel=\"nofollow\" data-no-translation=\"\" data-trp-gettext=\"\" data-no-translation-aria-label=\"\">In den Warenkorb<\/a><span id=\"woocommerce_loop_add_to_cart_link_describedby_1647\" class=\"screen-reader-text\">\n\t<\/span>\n<\/li>\n<li class=\"product type-product post-1642 status-publish instock product_cat-ergotherapie product_cat-fysiotherapie product_cat-patiententransfer product_cat-verpleegkundige has-post-thumbnail virtual purchasable product-type-simple\">\n\t<a href=\"https:\/\/niveb.com\/de_de\/produkt\/niveb-kinaesthetics-basiscursus-2026-04-24\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/niveb.com\/wp-content\/uploads\/2025\/06\/NIVEB_DRK-400x400.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/niveb.com\/wp-content\/uploads\/2025\/06\/NIVEB_DRK-400x400.jpg 400w, https:\/\/niveb.com\/wp-content\/uploads\/2025\/06\/NIVEB_DRK-150x150.jpg 150w, https:\/\/niveb.com\/wp-content\/uploads\/2025\/06\/NIVEB_DRK-100x100.jpg 100w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><h2 class=\"woocommerce-loop-product__title\">Niveb-Kinaesthetics Basiscursus 2026-04-28 M\u00f6nchengladbach<\/h2>\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>395.00<\/bdi><\/span><\/span>\n<\/a><a href=\"?add-to-cart=1642\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_1642\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"1642\" data-product_sku=\"\" aria-label=\"In den Warenkorb legen: \u201eNiveb-Kinaesthetics Basiscursus 2026-04-28 M\u00f6nchengladbach\u201c\" rel=\"nofollow\" data-no-translation=\"\" data-trp-gettext=\"\" data-no-translation-aria-label=\"\">In den Warenkorb<\/a><span id=\"woocommerce_loop_add_to_cart_link_describedby_1642\" class=\"screen-reader-text\">\n\t<\/span>\n<\/li>\n<li class=\"product type-product post-1625 status-publish last instock product_cat-ergotherapie product_cat-fysiotherapie product_cat-patiententransfer product_cat-verpleegkundige has-post-thumbnail virtual purchasable product-type-simple\">\n\t<a href=\"https:\/\/niveb.com\/de_de\/produkt\/niveb-kinaesthetics-basiscursus-2026-01-13\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/niveb.com\/wp-content\/uploads\/2022\/04\/4050-4-400x400.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/niveb.com\/wp-content\/uploads\/2022\/04\/4050-4-400x400.jpg 400w, https:\/\/niveb.com\/wp-content\/uploads\/2022\/04\/4050-4-150x150.jpg 150w, https:\/\/niveb.com\/wp-content\/uploads\/2022\/04\/4050-4-100x100.jpg 100w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><h2 class=\"woocommerce-loop-product__title\">Niveb-Kinaesthetics Basiscursus 2026-01-13 Bochum<\/h2>\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>395.00<\/bdi><\/span><\/span>\n<\/a><a href=\"?add-to-cart=1625\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_1625\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"1625\" data-product_sku=\"\" aria-label=\"In den Warenkorb legen: \u201eNiveb-Kinaesthetics Basiscursus 2026-01-13 Bochum\u201c\" rel=\"nofollow\" data-no-translation=\"\" data-trp-gettext=\"\" data-no-translation-aria-label=\"\">In den Warenkorb<\/a><span id=\"woocommerce_loop_add_to_cart_link_describedby_1625\" class=\"screen-reader-text\">\n\t<\/span>\n<\/li>\n<\/ul>\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0f870be elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0f870be\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6d48819\" data-id=\"6d48819\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d94f8b7 elementor-widget elementor-widget-heading\" data-id=\"d94f8b7\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Warum Niveb w\u00e4hlen?<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-84c9412 elementor-widget-divider--separator-type-pattern elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"84c9412\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\" style=\"--divider-pattern-url: url(&quot;data:image\/svg+xml,%3Csvg xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039; preserveAspectRatio=&#039;none&#039; overflow=&#039;visible&#039; height=&#039;100%&#039; viewBox=&#039;0 0 24 24&#039; fill=&#039;none&#039; stroke=&#039;black&#039; stroke-width=&#039;3&#039; stroke-linecap=&#039;square&#039; stroke-miterlimit=&#039;10&#039;%3E%3Cpath d=&#039;M0,6c6,0,6,13,12,13S18,6,24,6&#039;\/%3E%3C\/svg%3E&quot;);\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ea13c1e elementor-widget elementor-widget-text-editor\" data-id=\"ea13c1e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Niveb ist bekannt f\u00fcr seinen praxisorientierten Ansatz und erfahrene Trainer. Die Schulungen sind so konzipiert, dass sie direkt anwendbare F\u00e4higkeiten vermitteln, die Pflegekr\u00e4fte in ihre t\u00e4gliche Arbeit integrieren k\u00f6nnen. Durch die Teilnahme an den Schulungen von Niveb investieren Sie sowohl in Ihre eigene berufliche Entwicklung als auch in die Qualit\u00e4t der von Ihnen geleisteten Pflege.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-468a6a40 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"468a6a40\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-268c8ada\" data-id=\"268c8ada\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-31e47644 elementor-widget elementor-widget-heading\" data-id=\"31e47644\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Heute lernen, morgen anwenden<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-64964c73 elementor-widget elementor-widget-text-editor\" data-id=\"64964c73\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Sie k\u00f6nnen die Theorie und F\u00e4higkeiten aus dem Unterricht sofort in die Praxis umsetzen und somit direkt in Ihrer eigenen Arbeit anwenden.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-4653e15\" data-id=\"4653e15\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-84dae84 elementor-widget elementor-widget-heading\" data-id=\"84dae84\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Mehrwert f\u00fcr den Arbeitgeber<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b2772ee elementor-widget elementor-widget-text-editor\" data-id=\"b2772ee\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Sie erhalten eine Schulung, die direkt auf eine reale Situation ausgerichtet ist. Ihr Arbeitgeber sieht daher sofort einen Nutzen f\u00fcr die Organisation.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-3673e73\" data-id=\"3673e73\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6434588 elementor-widget elementor-widget-heading\" data-id=\"6434588\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">F\u00fcr und von Pflegefachkr\u00e4ften<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-81883da elementor-widget elementor-widget-text-editor\" data-id=\"81883da\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Sie erhalten Unterricht von Fachkr\u00e4ften aus der Praxis und haben w\u00e4hrend des Unterrichts die M\u00f6glichkeit, sich mit anderen Fachkr\u00e4ften auszutauschen.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Innovatie in de zorg Niveb biedt een scala aan scholingen rondom het onderwerp kinesthetics, een revolutionaire benadering voor het verplaatsen van uw cli\u00ebnt binnen de gezondheidszorg en welzijnssector. Bekijk onze scholingen De mens als uitgangspunt voor goede zorg, zodat deze voor zowel werknemer als zorgvrager gezonder en menselijker wordt. Verplaats je client met gemak! Niveb [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-14","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/niveb.com\/de_de\/wp-json\/wp\/v2\/pages\/14"}],"collection":[{"href":"https:\/\/niveb.com\/de_de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/niveb.com\/de_de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/niveb.com\/de_de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/niveb.com\/de_de\/wp-json\/wp\/v2\/comments?post=14"}],"version-history":[{"count":241,"href":"https:\/\/niveb.com\/de_de\/wp-json\/wp\/v2\/pages\/14\/revisions"}],"predecessor-version":[{"id":1593,"href":"https:\/\/niveb.com\/de_de\/wp-json\/wp\/v2\/pages\/14\/revisions\/1593"}],"wp:attachment":[{"href":"https:\/\/niveb.com\/de_de\/wp-json\/wp\/v2\/media?parent=14"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}